{"id":8153,"date":"2022-07-15T12:04:23","date_gmt":"2022-07-15T10:04:23","guid":{"rendered":"https:\/\/gelsomilano.com\/?post_type=product&#038;p=8153"},"modified":"2022-07-15T12:10:05","modified_gmt":"2022-07-15T10:10:05","slug":"honolulu-100-seta-hair-band","status":"publish","type":"product","link":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/","title":{"rendered":"Honolulu 100% Seta Hair Band"},"content":{"rendered":"<p>Questa elegante fascia per capelli <span style=\"font-weight: 400;\">\u00e8 stata realizzata in lussuosa seta 100%, ipoallergenica, 19MM<\/span>. Il design esclusivo, innovativo e accattivante, regala un tocco sensuale ed elegante al tuo look ed una sensazione di essere a Honolulu.<\/p>\n<p>Il tocco delicato della nostra fascia in seta non dannegger\u00e0 mai i tuoi capelli grazie anche al morbido elastico ricoperto in seta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puoi usare la tua fascia per capelli di seta sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.<\/p>\n<p>Il design esclusivo, innovativo e accattivante, regala un tocco sensuale ed elegante. Questa elegante fascia <span style=\"font-weight: 400;\">\u00e8 stata realizzata in lussuosa seta 100%, ipoallergenica, 19MM.<\/span><\/p>\n<p>Il tocco delicato della nostra fascia per capelli di seta non dannegger\u00e0 mai i tuoi capelli grazie anche al morbido elastico ricoperto in seta. Avvolgere i capelli in seta prima di dormire o strofinare i capelli asciutti dopo il lavaggio \u00e8 davvero un metodo che le donne conoscono da decenni. Aggiungi una fascia in seta alla tua routine di bellezza e scopri i suoi benefici!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":8154,"template":"","meta":[],"product_cat":[250,252,261,259],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Honolulu 100% Seta Hair Band | Gelso Milano<\/title>\n<meta name=\"description\" content=\"Puoi usare la tua fascia per capelli di seta Honolulu sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honolulu 100% Seta Hair Band | Gelso Milano\" \/>\n<meta property=\"og:description\" content=\"Puoi usare la tua fascia per capelli di seta Honolulu sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/\" \/>\n<meta property=\"og:site_name\" content=\"Gelso Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T10:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gelsomilano.com\/wp-content\/uploads\/2022\/07\/DB-9330square.jpg?_t=1657879805\" \/>\n\t<meta property=\"og:image:width\" content=\"1668\" \/>\n\t<meta property=\"og:image:height\" content=\"2500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gelso Milano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/gelsomilano.com\/#organization\",\"name\":\"Gelso Milano\",\"url\":\"https:\/\/gelsomilano.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/gelsomilano.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gelsomilano.com\/wp-content\/uploads\/2019\/02\/logo-gelso.png\",\"contentUrl\":\"https:\/\/gelsomilano.com\/wp-content\/uploads\/2019\/02\/logo-gelso.png\",\"width\":304,\"height\":155,\"caption\":\"Gelso Milano\"},\"image\":{\"@id\":\"https:\/\/gelsomilano.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gelsomilano.com\/#website\",\"url\":\"https:\/\/gelsomilano.com\/\",\"name\":\"Gelso Milano\",\"description\":\"Discover the art of Italian artisanry, luxury of the best silk materials and unique eye catching designs with the Gelso Milano collection of the finest Italian silk pyjamas, accessories and bedding.\",\"publisher\":{\"@id\":\"https:\/\/gelsomilano.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gelsomilano.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#primaryimage\",\"url\":\"https:\/\/gelsomilano.com\/wp-content\/uploads\/2022\/07\/DB-9330square.jpg\",\"contentUrl\":\"https:\/\/gelsomilano.com\/wp-content\/uploads\/2022\/07\/DB-9330square.jpg\",\"width\":1668,\"height\":2500,\"caption\":\"silk hair band\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#webpage\",\"url\":\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/\",\"name\":\"Honolulu 100% Seta Hair Band | Gelso Milano\",\"isPartOf\":{\"@id\":\"https:\/\/gelsomilano.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#primaryimage\"},\"datePublished\":\"2022-07-15T10:04:23+00:00\",\"dateModified\":\"2022-07-15T10:10:05+00:00\",\"description\":\"Puoi usare la tua fascia per capelli di seta Honolulu sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.\",\"breadcrumb\":{\"@id\":\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gelsomilano.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/gelsomilano.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Honolulu 100% Seta Hair Band\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honolulu 100% Seta Hair Band | Gelso Milano","description":"Puoi usare la tua fascia per capelli di seta Honolulu sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/","og_locale":"it_IT","og_type":"article","og_title":"Honolulu 100% Seta Hair Band | Gelso Milano","og_description":"Puoi usare la tua fascia per capelli di seta Honolulu sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.","og_url":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/","og_site_name":"Gelso Milano","article_modified_time":"2022-07-15T10:10:05+00:00","og_image":[{"width":1668,"height":2500,"url":"https:\/\/gelsomilano.com\/wp-content\/uploads\/2022\/07\/DB-9330square.jpg?_t=1657879805","type":"image\/jpeg"}],"author":"Gelso Milano","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/gelsomilano.com\/#organization","name":"Gelso Milano","url":"https:\/\/gelsomilano.com\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gelsomilano.com\/#\/schema\/logo\/image\/","url":"https:\/\/gelsomilano.com\/wp-content\/uploads\/2019\/02\/logo-gelso.png","contentUrl":"https:\/\/gelsomilano.com\/wp-content\/uploads\/2019\/02\/logo-gelso.png","width":304,"height":155,"caption":"Gelso Milano"},"image":{"@id":"https:\/\/gelsomilano.com\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/gelsomilano.com\/#website","url":"https:\/\/gelsomilano.com\/","name":"Gelso Milano","description":"Discover the art of Italian artisanry, luxury of the best silk materials and unique eye catching designs with the Gelso Milano collection of the finest Italian silk pyjamas, accessories and bedding.","publisher":{"@id":"https:\/\/gelsomilano.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gelsomilano.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#primaryimage","url":"https:\/\/gelsomilano.com\/wp-content\/uploads\/2022\/07\/DB-9330square.jpg","contentUrl":"https:\/\/gelsomilano.com\/wp-content\/uploads\/2022\/07\/DB-9330square.jpg","width":1668,"height":2500,"caption":"silk hair band"},{"@type":"WebPage","@id":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#webpage","url":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/","name":"Honolulu 100% Seta Hair Band | Gelso Milano","isPartOf":{"@id":"https:\/\/gelsomilano.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#primaryimage"},"datePublished":"2022-07-15T10:04:23+00:00","dateModified":"2022-07-15T10:10:05+00:00","description":"Puoi usare la tua fascia per capelli di seta Honolulu sia per un look esclusivo che per un look casual ed essere sicura che sarai splendida e comoda.","breadcrumb":{"@id":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gelsomilano.com\/it\/shop\/honolulu-100-seta-hair-band\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gelsomilano.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/gelsomilano.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Honolulu 100% Seta Hair Band"}]}]}},"_links":{"self":[{"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/product\/8153"}],"collection":[{"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/media\/8154"}],"wp:attachment":[{"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/media?parent=8153"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/product_cat?post=8153"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gelsomilano.com\/it\/wp-json\/wp\/v2\/product_tag?post=8153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}